{"id":1824,"date":"2024-03-01T13:35:27","date_gmt":"2024-03-01T13:35:27","guid":{"rendered":"https:\/\/www.kein-alter-hut.de\/?p=1824"},"modified":"2024-07-10T12:09:33","modified_gmt":"2024-07-10T12:09:33","slug":"eine-ganze-welt-in-einem-wassertropfen","status":"publish","type":"post","link":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/","title":{"rendered":"Eine ganze Welt in einem Wassertropfen"},"content":{"rendered":"\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe title=\"Wassernetz im B\u00fcrgerb\u00fcro\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/dYsr7griV08?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4-scaled.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"730\" height=\"1024\" src=\"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4-730x1024.jpeg\" alt=\"\" class=\"wp-image-1825\" srcset=\"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4-730x1024.jpeg 730w, https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4-214x300.jpeg 214w, https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4-768x1078.jpeg 768w, https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4-1095x1536.jpeg 1095w, https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4-1460x2048.jpeg 1460w, https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4-scaled.jpeg 1824w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1826,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[],"class_list":["post-1824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-tegel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eine ganze Welt in einem Wassertropfen - Sven Meyer MdA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eine ganze Welt in einem Wassertropfen - Sven Meyer MdA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/\" \/>\n<meta property=\"og:site_name\" content=\"Sven Meyer MdA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SvenMeyerReinickendorf\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T13:35:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-10T12:09:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4_headline.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2288\" \/>\n\t<meta property=\"og:image:height\" content=\"704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/#\\\/schema\\\/person\\\/0e854002ba9ffda5baf08e0f9af0ce1c\"},\"headline\":\"Eine ganze Welt in einem Wassertropfen\",\"datePublished\":\"2024-03-01T13:35:27+00:00\",\"dateModified\":\"2024-07-10T12:09:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/\"},\"wordCount\":14,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Weltwassertag-22.3.24-A4_headline.jpeg\",\"articleSection\":{\"1\":\"Tegel\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/\",\"url\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/\",\"name\":\"Eine ganze Welt in einem Wassertropfen - Sven Meyer MdA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Weltwassertag-22.3.24-A4_headline.jpeg\",\"datePublished\":\"2024-03-01T13:35:27+00:00\",\"dateModified\":\"2024-07-10T12:09:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/#\\\/schema\\\/person\\\/0e854002ba9ffda5baf08e0f9af0ce1c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Weltwassertag-22.3.24-A4_headline.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Weltwassertag-22.3.24-A4_headline.jpeg\",\"width\":2288,\"height\":704},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/2024\\\/03\\\/01\\\/eine-ganze-welt-in-einem-wassertropfen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eine ganze Welt in einem Wassertropfen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/#website\",\"url\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/\",\"name\":\"Sven Meyer MdA\",\"description\":\"Sven Meyer - Ihr Abgeordneter f\u00fcr Wittenau, Waidmannslust, Borsigwalde und Tegel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/#\\\/schema\\\/person\\\/0e854002ba9ffda5baf08e0f9af0ce1c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c46849f5dee5060ebc9f63f2434fb89c496cdde2d971d8684cb05ccf66e9936c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c46849f5dee5060ebc9f63f2434fb89c496cdde2d971d8684cb05ccf66e9936c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c46849f5dee5060ebc9f63f2434fb89c496cdde2d971d8684cb05ccf66e9936c?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.kein-alter-hut.de\"],\"url\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/author\\\/sven\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eine ganze Welt in einem Wassertropfen - Sven Meyer MdA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/","og_locale":"de_DE","og_type":"article","og_title":"Eine ganze Welt in einem Wassertropfen - Sven Meyer MdA","og_url":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/","og_site_name":"Sven Meyer MdA","article_publisher":"https:\/\/www.facebook.com\/SvenMeyerReinickendorf\/","article_published_time":"2024-03-01T13:35:27+00:00","article_modified_time":"2024-07-10T12:09:33+00:00","og_image":[{"width":2288,"height":704,"url":"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4_headline.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/#article","isPartOf":{"@id":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/"},"author":{"name":"admin","@id":"https:\/\/www.kein-alter-hut.de\/#\/schema\/person\/0e854002ba9ffda5baf08e0f9af0ce1c"},"headline":"Eine ganze Welt in einem Wassertropfen","datePublished":"2024-03-01T13:35:27+00:00","dateModified":"2024-07-10T12:09:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/"},"wordCount":14,"commentCount":0,"image":{"@id":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4_headline.jpeg","articleSection":{"1":"Tegel"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/","url":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/","name":"Eine ganze Welt in einem Wassertropfen - Sven Meyer MdA","isPartOf":{"@id":"https:\/\/www.kein-alter-hut.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/#primaryimage"},"image":{"@id":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4_headline.jpeg","datePublished":"2024-03-01T13:35:27+00:00","dateModified":"2024-07-10T12:09:33+00:00","author":{"@id":"https:\/\/www.kein-alter-hut.de\/#\/schema\/person\/0e854002ba9ffda5baf08e0f9af0ce1c"},"breadcrumb":{"@id":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/#primaryimage","url":"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4_headline.jpeg","contentUrl":"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2024\/03\/Weltwassertag-22.3.24-A4_headline.jpeg","width":2288,"height":704},{"@type":"BreadcrumbList","@id":"https:\/\/www.kein-alter-hut.de\/index.php\/2024\/03\/01\/eine-ganze-welt-in-einem-wassertropfen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kein-alter-hut.de\/"},{"@type":"ListItem","position":2,"name":"Eine ganze Welt in einem Wassertropfen"}]},{"@type":"WebSite","@id":"https:\/\/www.kein-alter-hut.de\/#website","url":"https:\/\/www.kein-alter-hut.de\/","name":"Sven Meyer MdA","description":"Sven Meyer - Ihr Abgeordneter f\u00fcr Wittenau, Waidmannslust, Borsigwalde und Tegel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kein-alter-hut.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.kein-alter-hut.de\/#\/schema\/person\/0e854002ba9ffda5baf08e0f9af0ce1c","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c46849f5dee5060ebc9f63f2434fb89c496cdde2d971d8684cb05ccf66e9936c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c46849f5dee5060ebc9f63f2434fb89c496cdde2d971d8684cb05ccf66e9936c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c46849f5dee5060ebc9f63f2434fb89c496cdde2d971d8684cb05ccf66e9936c?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.kein-alter-hut.de"],"url":"https:\/\/www.kein-alter-hut.de\/index.php\/author\/sven\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/posts\/1824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/comments?post=1824"}],"version-history":[{"count":2,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/posts\/1824\/revisions"}],"predecessor-version":[{"id":2377,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/posts\/1824\/revisions\/2377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/media\/1826"}],"wp:attachment":[{"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/media?parent=1824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/categories?post=1824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/tags?post=1824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}