{"id":3555,"date":"2026-05-13T13:51:18","date_gmt":"2026-05-13T13:51:18","guid":{"rendered":"https:\/\/www.kein-alter-hut.de\/?post_type=tribe_events&#038;p=3555"},"modified":"2026-05-13T13:51:18","modified_gmt":"2026-05-13T13:51:18","slug":"impressionen-erkundungen-vernissage-david-henderson","status":"publish","type":"tribe_events","link":"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/","title":{"rendered":"&#8222;Impressionen &#8211; Erkundungen&#8220; Vernissage David Henderson"},"content":{"rendered":"<p><a href=\"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2026\/05\/Plakat-Vernissage-Henderson-Facebook.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-3556\" src=\"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2026\/05\/Plakat-Vernissage-Henderson-Facebook-300x251.png\" alt=\"\" width=\"613\" height=\"513\" srcset=\"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2026\/05\/Plakat-Vernissage-Henderson-Facebook-300x251.png 300w, https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2026\/05\/Plakat-Vernissage-Henderson-Facebook-768x644.png 768w, https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2026\/05\/Plakat-Vernissage-Henderson-Facebook.png 940w\" sizes=\"(max-width: 613px) 100vw, 613px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-3555","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Impressionen - Erkundungen&quot; Vernissage David Henderson - Sven Meyer MdA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Impressionen - Erkundungen&quot; Vernissage David Henderson - Sven Meyer MdA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/\" \/>\n<meta property=\"og:site_name\" content=\"Sven Meyer MdA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SvenMeyerReinickendorf\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2026\/05\/Plakat-Vernissage-Henderson-Facebook.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/event\\\/impressionen-erkundungen-vernissage-david-henderson\\\/\",\"url\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/event\\\/impressionen-erkundungen-vernissage-david-henderson\\\/\",\"name\":\"\\\"Impressionen - Erkundungen\\\" Vernissage David Henderson - Sven Meyer MdA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/event\\\/impressionen-erkundungen-vernissage-david-henderson\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/event\\\/impressionen-erkundungen-vernissage-david-henderson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Plakat-Vernissage-Henderson-Facebook-300x251.png\",\"datePublished\":\"2026-05-13T13:51:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/event\\\/impressionen-erkundungen-vernissage-david-henderson\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/event\\\/impressionen-erkundungen-vernissage-david-henderson\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/event\\\/impressionen-erkundungen-vernissage-david-henderson\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Plakat-Vernissage-Henderson-Facebook.png\",\"contentUrl\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Plakat-Vernissage-Henderson-Facebook.png\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/event\\\/impressionen-erkundungen-vernissage-david-henderson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/index.php\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8222;Impressionen &#8211; Erkundungen&#8220; Vernissage David Henderson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/#website\",\"url\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/\",\"name\":\"Sven Meyer MdA\",\"description\":\"Sven Meyer - Ihr Abgeordneter f\u00fcr Wittenau, Waidmannslust, Borsigwalde und Tegel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kein-alter-hut.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Impressionen - Erkundungen\" Vernissage David Henderson - Sven Meyer MdA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/","og_locale":"de_DE","og_type":"article","og_title":"\"Impressionen - Erkundungen\" Vernissage David Henderson - Sven Meyer MdA","og_url":"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/","og_site_name":"Sven Meyer MdA","article_publisher":"https:\/\/www.facebook.com\/SvenMeyerReinickendorf\/","og_image":[{"width":940,"height":788,"url":"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2026\/05\/Plakat-Vernissage-Henderson-Facebook.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/","url":"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/","name":"\"Impressionen - Erkundungen\" Vernissage David Henderson - Sven Meyer MdA","isPartOf":{"@id":"https:\/\/www.kein-alter-hut.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/#primaryimage"},"image":{"@id":"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2026\/05\/Plakat-Vernissage-Henderson-Facebook-300x251.png","datePublished":"2026-05-13T13:51:18+00:00","breadcrumb":{"@id":"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/#primaryimage","url":"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2026\/05\/Plakat-Vernissage-Henderson-Facebook.png","contentUrl":"https:\/\/www.kein-alter-hut.de\/wp-content\/uploads\/2026\/05\/Plakat-Vernissage-Henderson-Facebook.png","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/www.kein-alter-hut.de\/index.php\/event\/impressionen-erkundungen-vernissage-david-henderson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kein-alter-hut.de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.kein-alter-hut.de\/index.php\/events\/"},{"@type":"ListItem","position":3,"name":"&#8222;Impressionen &#8211; Erkundungen&#8220; Vernissage David Henderson"}]},{"@type":"WebSite","@id":"https:\/\/www.kein-alter-hut.de\/#website","url":"https:\/\/www.kein-alter-hut.de\/","name":"Sven Meyer MdA","description":"Sven Meyer - Ihr Abgeordneter f\u00fcr Wittenau, Waidmannslust, Borsigwalde und Tegel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kein-alter-hut.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/3555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/3555\/revisions"}],"predecessor-version":[{"id":3557,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/3555\/revisions\/3557"}],"wp:attachment":[{"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/media?parent=3555"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/tags?post=3555"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.kein-alter-hut.de\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=3555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}